{"id":325,"date":"2024-09-30T07:09:36","date_gmt":"2024-09-30T07:09:36","guid":{"rendered":"https:\/\/ladrondelunas.es\/blog\/?p=325"},"modified":"2024-09-17T10:07:48","modified_gmt":"2024-09-17T10:07:48","slug":"que-es-la-vendimia","status":"publish","type":"post","link":"https:\/\/ladrondelunas.es\/blog\/uncategorized\/que-es-la-vendimia\/","title":{"rendered":"\u00bfQU\u00c9 ES LA VENDIMIA?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Uno de los procesos m\u00e1s importantes en la elaboraci\u00f3n del vino.<\/h2>\n\n\n\n<p>La vendimia es el <strong>proceso de recolecci\u00f3n de la uva<\/strong>, fundamental en la elaboraci\u00f3n del vino. Tiene lugar una vez que las <strong>uvas<\/strong> han alcanzado su <strong>punto \u00f3ptimo de maduraci\u00f3n<\/strong>, lo que var\u00eda seg\u00fan la variedad de uva, el clima y la regi\u00f3n. <\/p>\n\n\n\n<p>Tradicionalmente, la vendimia <strong>se realizaba a mano<\/strong>, lo que permit\u00eda <strong>seleccionar cuidadosamente las uvas en mejor estado<\/strong>. Aunque hoy en d\u00eda muchas bodegas utilizan m\u00e1quinas para agilizar el proceso, en algunas zonas se sigue optando por la <strong>vendimia manual<\/strong>, sobre todo en vi\u00f1edos donde el <strong>terreno es dif\u00edcil o cuando se busca un control<\/strong>.<\/p>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/C-qKWG4vf8K\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/C-qKWG4vf8K\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/C-qKWG4vf8K\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de Bodegas Ladro\u0301n de Lunas (@ladrondelunas)<\/a><\/p><\/div><\/blockquote>\n<script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<p><\/p>\n\n\n\n<p>Este evento es m\u00e1s que un simple trabajo agr\u00edcola; en muchas regiones vitivin\u00edcolas, la vendimia se ha convertido en una <strong>fiesta tradicional que re\u00fane a las comunidades locales<\/strong> y turistas en torno al vino y sus tradiciones. En Espa\u00f1a, por ejemplo, algunas de las vendimias m\u00e1s conocidas se celebran en regiones como La Rioja, Ribera del Duero o Jerez. En Francia, en regiones como Burdeos o Borgo\u00f1a, la vendimia tambi\u00e9n tiene <strong>gran relevancia cultural y econ\u00f3mica<\/strong>.<\/p>\n\n\n\n<p>El <strong>momento exacto<\/strong> para comenzar la vendimia <strong>depende de factores como el equilibrio entre az\u00facar y acidez en la uva<\/strong>. El en\u00f3logo, a trav\u00e9s de <strong>an\u00e1lisis qu\u00edmicos y catas<\/strong>, determina el momento id\u00f3neo. La <strong>recolecci\u00f3n temprana puede dar vinos m\u00e1s frescos y ligeros<\/strong>, mientras que una <strong>cosecha m\u00e1s tard\u00eda<\/strong> suele producir <strong>vinos m\u00e1s potentes y dulces.<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.reyesgrupo.com\/blog\/vinos-5\/la-influencia-de-la-luna-en-la-viticultura-y-la-vinificacion-758#:~:text=La%20elecci%C3%B3n%20del%20momento%20de,para%20ciertos%20tipos%20de%20uvas.\" data-type=\"link\" data-id=\"https:\/\/www.reyesgrupo.com\/blog\/vinos-5\/la-influencia-de-la-luna-en-la-viticultura-y-la-vinificacion-758#:~:text=La%20elecci%C3%B3n%20del%20momento%20de,para%20ciertos%20tipos%20de%20uvas.\">Los ciclos lunares<\/a><\/strong> tambi\u00e9n pueden influir en la vinificaci\u00f3n. La elecci\u00f3n del momento de la vendimia tambi\u00e9n est\u00e1 relacionada con los ciclos lunares. Algunos viticultores creen que las <strong>uvas cosechadas durante la luna<\/strong> llena tienen un <strong>mayor potencial de calidad<\/strong>, mientras que otros prefieren la luna nueva para ciertos tipos de uvas. Estos enfoques pueden variar seg\u00fan las preferencias individuales y las tradiciones regionales.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Bodega_Ladron_De_Lunas_Vinedo-819x1024.jpg\" alt=\"\" class=\"wp-image-327\" style=\"width:453px;height:auto\" srcset=\"https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Bodega_Ladron_De_Lunas_Vinedo-819x1024.jpg 819w, https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Bodega_Ladron_De_Lunas_Vinedo-240x300.jpg 240w, https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Bodega_Ladron_De_Lunas_Vinedo-768x960.jpg 768w, https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Bodega_Ladron_De_Lunas_Vinedo.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div>\n\n\n<p>En resumen, la <strong>vendimia es un proceso crucial en la producci\u00f3n del vino<\/strong> que combina tradici\u00f3n, t\u00e9cnica y celebraci\u00f3n, y tiene un impacto significativo en la calidad del producto final.<\/p>\n\n\n\n<p>En <strong><a href=\"https:\/\/www.ladrondelunas.es\/visitanos.php\" data-type=\"link\" data-id=\"https:\/\/www.ladrondelunas.es\/visitanos.php\">Ladr\u00f3n de Lunas<\/a><\/strong> sentimos especial conexi\u00f3n con estos procesos lunares, y no hemos tardado en plasmarlo en nuestros vinos. La \u00faltima adquisici\u00f3n es un vino blanco, madurado sobre l\u00edas, al que hemos bautizado bajo el nombre de <strong><em>Eclipse<\/em><\/strong>. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Vino_Blanco_Eclipse_Bodega_Ladron_De_Lunas-819x1024.jpg\" alt=\"\" class=\"wp-image-326\" style=\"width:451px;height:auto\" srcset=\"https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Vino_Blanco_Eclipse_Bodega_Ladron_De_Lunas-819x1024.jpg 819w, https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Vino_Blanco_Eclipse_Bodega_Ladron_De_Lunas-240x300.jpg 240w, https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Vino_Blanco_Eclipse_Bodega_Ladron_De_Lunas-768x960.jpg 768w, https:\/\/ladrondelunas.es\/blog\/wp-content\/uploads\/2024\/09\/Vino_Blanco_Eclipse_Bodega_Ladron_De_Lunas.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Os invitamos a probarlo y que pod\u00e1is experimentar su sabor, <strong>muy agradable, sabroso, untuoso y largo en boca<\/strong>. Y por supuesto, que lo disfrut\u00e9is.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los procesos m\u00e1s importantes en la elaboraci\u00f3n del vino. La vendimia es el proceso de recolecci\u00f3n de la uva, fundamental en la elaboraci\u00f3n del vino. Tiene lugar una vez que las uvas han alcanzado su punto \u00f3ptimo de maduraci\u00f3n, lo que var\u00eda seg\u00fan la variedad de uva, el clima y la regi\u00f3n. Tradicionalmente, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/ladrondelunas.es\/blog\/uncategorized\/que-es-la-vendimia\/\"> <span class=\"screen-reader-text\">\u00bfQU\u00c9 ES LA VENDIMIA?<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[9,18,16,109,19,111,110,113,36,88,23,112,77,6,87],"class_list":["post-325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-bodegas","tag-calidad","tag-curiosidades","tag-eclipse","tag-ladron-de-lunas-2","tag-largo-en-boca","tag-madurado-sobre-lias","tag-proceso-de-recoleccion","tag-sabores","tag-tradicional","tag-uva","tag-vendimia","tag-vinedo","tag-vino","tag-vino-blanco"],"_links":{"self":[{"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/posts\/325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/comments?post=325"}],"version-history":[{"count":3,"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/posts\/325\/revisions"}],"predecessor-version":[{"id":332,"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/posts\/325\/revisions\/332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/media\/327"}],"wp:attachment":[{"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/media?parent=325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/categories?post=325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ladrondelunas.es\/blog\/wp-json\/wp\/v2\/tags?post=325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}